{"id":19438,"date":"2019-07-12T09:36:37","date_gmt":"2019-07-12T07:36:37","guid":{"rendered":"https:\/\/irinakuehn.de\/?page_id=19438"},"modified":"2023-04-25T10:06:22","modified_gmt":"2023-04-25T08:06:22","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/irinakuehn.de\/en\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<div      class=\"vc_row wpb_row section vc_row-fluid  grid_section\" style='background-color:#ffffff; padding-top:60px; padding-bottom:45px; text-align:left;'><div class=\"section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid vc_inner\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"color: #3a3a3a;\">Die nachfolgende Datenschutzerkl\u00e4rung gilt f\u00fcr die Nutzung der Webseite<\/span> <a href=\"https:\/\/irinakuehn.de\/en\/\">www.irinakuehn.de<\/a> <span style=\"color: #3a3a3a;\">(nachfolgend \u201eWebsite\u201c). Wir messen dem Datenschutz gro\u00dfe Bedeutung bei. Die Erhebung und Verarbeitung Ihrer personenbezogenen Daten geschieht unter Beachtung der geltenden datenschutzrechtlichen Vorschriften, insbesondere der EU-Datenschutzgrundverordnung (DSGVO). WPersonenbezogene Daten werden auf dieser Webseite nur im technisch notwendigen Umfang oder zur Verarbeitung von Anfragen erhoben. In keinem Fall werden die erhobenen Daten verkauft oder aus anderen Gr\u00fcnden an Dritte weitergegeben. Diese Erkl\u00e4rung beschreibt, wie und zu welchem Zweck Ihre Daten erfasst und genutzt werden und welche Wahlm\u00f6glichkeiten Sie im Zusammenhang mit pers\u00f6nlichen Daten haben. Durch Ihre Verwendung dieser Website stimmen Sie der Erfassung, Nutzung und \u00dcbertragung Ihrer Daten gem\u00e4\u00df dieser Datenschutzerkl\u00e4rung zu.<\/span><\/p>\n<h2 id=\"dsg-general-controller\"><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Verantwortlich<\/span><\/h2>\n<p><span class=\"tsmcontroller\" style=\"color: #3a3a3a;\"><br \/>\nVerantwortliche Stelle f\u00fcr die Erhebung, Verarbeitung und Nutzung Ihrer personenbezogenen Daten im Sinne der DSGVO ist<\/span><\/p>\n<p><span class=\"tsmcontroller\" style=\"color: #3a3a3a;\">Irina K\u00fchn<br \/>\nc\/o Cyhn Media<br \/>\nIn den Ringelg\u00e4rten 24<br \/>\nD-70374 Stuttgart<br \/>\nE-Mail: mail@irinakuehn.de<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Sofern Sie der Erhebung, Verarbeitung oder Nutzung Ihrer Daten durch uns nach Ma\u00dfgabe dieser Datenschutzbestimmungen insgesamt oder f\u00fcr einzelne Ma\u00dfnahmen widersprechen wollen, k\u00f6nnen Sie Ihren Widerspruch an oben genannte verantwortliche Stelle richten.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Datenverarbeitung auf dieser Internetseite<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nDie Website irinakuehn.de erhebt und speichert automatisch in den Server-Logfiles Informationen, die Ihr Browser an uns \u00fcbermittelt. Dies sind:<\/span><br \/>\n<span style=\"color: #3a3a3a;\">&#8211; Browsertyp\/ -version<\/span><br \/>\n<span style=\"color: #3a3a3a;\">&#8211; verwendetes Betriebssystem<\/span><br \/>\n<span style=\"color: #3a3a3a;\">&#8211; Referrer URL (die zuvor besuchte Seite)<\/span><br \/>\n<span style=\"color: #3a3a3a;\">&#8211; Hostname des zugreifenden Rechners (IP-Adresse)<\/span><br \/>\n<span style=\"color: #3a3a3a;\">&#8211; Uhrzeit der Serveranfrage<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Diese Daten sind nicht bestimmten Personen zuordenbar. Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen, die Daten werden zudem nach einer statistischen Auswertung gel\u00f6scht.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Cookies<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nDie Internetseiten verwenden an mehreren Stellen so genannte Cookies. Sie dienen dazu, das Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert. Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Verweise und Links<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nBei direkten oder indirekten Verweisen auf fremde Internetseiten (\u201eLinks\u201c), die au\u00dferhalb des Verantwortungsbereiches des Autors liegen, w\u00fcrde eine Haftungsverpflichtung ausschlie\u00dflich in dem Fall in Kraft treten, in dem der Autor von den Inhalten Kenntnis hat und es ihm technisch m\u00f6glich und zumutbar w\u00e4re, die Nutzung im Falle rechtswidriger Inhalte zu verhindern. Der Autor erkl\u00e4rt hiermit ausdr\u00fccklich, dass zum Zeitpunkt der Linksetzung keine illegalen Inhalte auf den zu verlinkenden Seiten erkennbar waren. Auf die aktuelle und zuk\u00fcnftige Gestaltung, die Inhalte oder die Urheberschaft der gelinkten\/verkn\u00fcpften Seiten hat der Autor keinerlei Einfluss. Deshalb distanziert er sich hiermit ausdr\u00fccklich von allen Inhalten aller gelinkten \/verkn\u00fcpften Seiten, die nach der Linksetzung ver\u00e4ndert wurden. Diese Feststellung gilt f\u00fcr alle innerhalb des eigenen Internetangebotes gesetzten Links und Verweise sowie f\u00fcr Fremdeintr\u00e4ge in vom Autor eingerichteten G\u00e4steb\u00fcchern, Diskussionsforen und Mailinglisten. F\u00fcr illegale, fehlerhafte oder unvollst\u00e4ndige Inhalte und insbesondere f\u00fcr Sch\u00e4den, die aus der Nutzung oder Nichtnutzung solcherart dargebotener Informationen entstehen, haftet allein der Anbieter der Seite, auf welche verwiesen wurde, nicht derjenige, der \u00fcber Links auf die jeweilige Ver\u00f6ffentlichung lediglich verweist.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Google Analytics<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nDiese Website benutzt Google Analytics, einen Webanalysedienst der Googe Inc. (\u201eGoogle\u201c) Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glicht. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website (einschlie\u00dflich Ihrer IP-Adresse) wird an einen Server der Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben oder soweit Dritte diese Daten im Auftrag von Google verarbeiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten der Google in Verbindung bringen. Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung Ihrer Browser Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website voll umf\u00e4nglich nutzen k\u00f6nnen. Durch die Nutzung dieser Website erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Der Erhebung und Nutzung Ihrer IP-Adresse durch Google Analytics k\u00f6nnen Sie jederzeit mit Wirkung f\u00fcr die Zukunft widersprechen. N\u00e4here Informationen hierzu finden Sie unter\u00a0 http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de. Wir weisen Sie darauf hin, dass auf dieser Webseite Google Analytics um den Code \u201egat._anonymizeIp();\u201c erweitert wurde, um eine anonymisierte Erfassung von IP-Adressen zu gew\u00e4hrleisten.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Kontaktm\u00f6glichkeit \u00fcber die Internetseite<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nDie Internetseite irinakuehn.de enth\u00e4lt aufgrund von gesetzlichen Vorschriften Angaben, die eine schnelle elektronische Kontaktaufnahme sowie eine unmittelbare Kommunikation mit uns erm\u00f6glichen, was ebenfalls eine allgemeine Adresse der sogenannten elektronischen Post (E-Mail-Adresse) umfasst. Sofern eine betroffene Person per E-Mail oder \u00fcber ein Kontaktformular den Kontakt mit dem f\u00fcr die Verarbeitung Verantwortlichen aufnimmt, werden die von der betroffenen Person \u00fcbermittelten personenbezogenen Daten automatisch gespeichert. Solche auf freiwilliger Basis von einer betroffenen Person an den f\u00fcr die Verarbeitung Verantwortlichen \u00fcbermittelten personenbezogenen Daten werden f\u00fcr Zwecke der Bearbeitung oder der Kontaktaufnahme zur betroffenen Person gespeichert. Es erfolgt keine Weitergabe dieser personenbezogenen Daten an Dritte.<\/span><\/p>\n<h2 id=\"dsg-newsletter-provider-mailchimp\"><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Newsletter \/\/ Mailchimp<\/span><\/h2>\n<p><span class=\"ts-muster-content\" style=\"color: #3a3a3a;\"><br \/>\nDer Versand der Newsletter erfolgt mittels des Versanddienstleisters \u201eMailChimp\u201c, einer Newsletterversandplattform des US-Anbieters Rocket Science Group, LLC, 675 Ponce De Leon Ave NE #5000, Atlanta, GA 30308, USA. Die Datenschutzbestimmungen des Versanddienstleisters k\u00f6nnen Sie hier einsehen: <a style=\"color: #3a3a3a;\" href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/mailchimp.com\/legal\/privacy\/<\/a>. The Rocket Science Group LLC d\/b\/a MailChimp ist unter dem Privacy-Shield-Abkommen zertifiziert und bietet hierdurch eine Garantie, das europ\u00e4isches Datenschutzniveau einzuhalten (<a style=\"color: #3a3a3a;\" href=\"https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TO6hAAG&amp;status=Active\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TO6hAAG&amp;status=Active<\/a>). Der Versanddienstleister wird auf Grundlage unserer berechtigten Interessen gem. Art. 6 Abs. 1 lit. f DSGVO und eines Auftragsverarbeitungsvertrages gem. Art. 28 Abs. 3 S. 1 DSGVO eingesetzt.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Der Versanddienstleister kann die Daten der Empf\u00e4nger in pseudonymer Form, d.h. ohne Zuordnung zu einem Nutzer, zur Optimierung oder Verbesserung der eigenen Services nutzen, z.B. zur technischen Optimierung des Versandes und der Darstellung der Newsletter oder f\u00fcr statistische Zwecke verwenden. Der Versanddienstleister nutzt die Daten unserer Newsletterempf\u00e4nger jedoch nicht, um diese selbst anzuschreiben oder um die Daten an Dritte weiterzugeben.<\/span><\/p>\n<h2 id=\"dsg-newsletter-analytics\"><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Newsletter \/\/ Erfolgsmessung<\/span><\/h2>\n<p><span class=\"ts-muster-content\" style=\"color: #3a3a3a;\"><br \/>\nDie Newsletter enthalten einen sog. \u201eweb-beacon\u201c, d.h. eine pixelgro\u00dfe Datei, die beim \u00d6ffnen des Newsletters von unserem Server, bzw. sofern wir einen Versanddienstleister einsetzen, von dessen Server abgerufen wird. Im Rahmen dieses Abrufs werden zun\u00e4chst technische Informationen, wie Informationen zum Browser und Ihrem System, als auch Ihre IP-Adresse und Zeitpunkt des Abrufs erhoben.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Diese Informationen werden zur technischen Verbesserung der Services anhand der technischen Daten oder der Zielgruppen und ihres Leseverhaltens anhand derer Abruforte (die mit Hilfe der IP-Adresse bestimmbar sind) oder der Zugriffszeiten genutzt. Zu den statistischen Erhebungen geh\u00f6rt ebenfalls die Feststellung, ob die Newsletter ge\u00f6ffnet werden, wann sie ge\u00f6ffnet werden und welche Links geklickt werden. Diese Informationen k\u00f6nnen aus technischen Gr\u00fcnden zwar den einzelnen Newsletterempf\u00e4ngern zugeordnet werden. Es ist jedoch weder unser Bestreben, noch, sofern eingesetzt, das des Versanddienstleisters, einzelne Nutzer zu beobachten. Die Auswertungen dienen uns viel mehr dazu, die Lesegewohnheiten unserer Nutzer zu erkennen und unsere Inhalte auf sie anzupassen oder unterschiedliche Inhalte entsprechend den Interessen unserer Nutzer zu versenden.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Ein getrennter Widerruf der Erfolgsmessung ist leider nicht m\u00f6glich, in diesem Fall muss das gesamte Newsletterabonnement gek\u00fcndigt werden.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #3a3a3a;\">Google Web Fonts<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nDiese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Web Fonts, die von Google bereitgestellt werden. Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Google aufnehmen. Hierdurch erlangt Google Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse unsere Website aufgerufen wurde. Die Nutzung von Google Web Fonts erfolgt im Interesse einer einheitlichen und ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Wenn Ihr Browser Web Fonts nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem Computer genutzt.<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">Weitere Informationen zu Google Web Fonts finden Sie unter https:\/\/developers.google.com\/fonts\/faq und in der Datenschutzerkl\u00e4rung von Google: https:\/\/www.google.com\/policies\/privacy\/.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Google reCAPTCHA<\/span><\/h2>\n<div>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nWir nutzen \u201eGoogle reCAPTCHA\u201c (im Folgenden \u201ereCAPTCHA\u201c) auf dieser Website. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/span><br \/>\n<span style=\"color: #3a3a3a;\"><br \/>\nMit reCAPTCHA soll \u00fcberpr\u00fcft werden, ob die Dateneingabe auf dieser Website (z.\u00a0B. in einem Kontaktformular) durch einen Menschen oder durch ein automatisiertes Programm erfolgt. Hierzu analysiert reCAPTCHA das Verhalten des Websitebesuchers anhand verschiedener Merkmale. Diese Analyse beginnt automatisch, sobald der Websitebesucher die Website betritt. Zur Analyse wertet reCAPTCHA verschiedene Informationen aus (z.\u00a0B. IP-Adresse, Verweildauer des Websitebesuchers auf der Website oder vom Nutzer get\u00e4tigte Mausbewegungen). Die bei der Analyse erfassten Daten werden an Google weitergeleitet.<\/span><br \/>\n<span style=\"color: #3a3a3a;\"><br \/>\nDie reCAPTCHA-Analysen laufen vollst\u00e4ndig im Hintergrund. Websitebesucher werden nicht darauf hingewiesen, dass eine Analyse stattfindet.<\/span><br \/>\n<span style=\"color: #3a3a3a;\"><br \/>\nDie Speicherung und Analyse der Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse daran, seine Webangebote vor missbr\u00e4uchlicher automatisierter Aussp\u00e4hung und vor SPAM zu sch\u00fctzen. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.\u00a0B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/span><br \/>\n<span style=\"color: #3a3a3a;\"><br \/>\nWeitere Informationen zu Google reCAPTCHA entnehmen Sie den Google-Datenschutzbestimmungen und den Google Nutzungsbedingungen unter folgenden Links:\u00a0<a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>\u00a0und\u00a0<a href=\"https:\/\/policies.google.com\/terms?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/terms?hl=de<\/a>.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Onlinepr\u00e4senzen in sozialen Medien<\/span><\/h2>\n<div><span style=\"color: #3a3a3a;\"><br \/>\nWir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke und Plattformen, um mit den dort aktiven Kunden, Interessenten und Nutzern kommunizieren und sie dort \u00fcber unsere Leistungen informieren zu k\u00f6nnen. Beim Aufruf der jeweiligen Netzwerke und Plattformen gelten die Gesch\u00e4ftsbedingungen und die Datenverarbeitungsrichtlinien deren jeweiligen Betreiber.<\/span><\/div>\n<p>Verwendung von Facebook Social Plugins<\/p>\n<p><span style=\"color: #3a3a3a;\">Wir nutzen auf Grundlage unserer berechtigten Interessen (d.h. Interesse an der Analyse, Optimierung und wirtschaftlichem Betrieb unseres Onlineangebotes im Sinne des Art. 6 Abs. 1 lit. f. DSGVO) Social Plugins (&#8222;Plugins&#8220;) des sozialen Netzwerkes facebook.com, welches von der Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland betrieben wird (&#8222;Facebook&#8220;). Die Plugins k\u00f6nnen Interaktionselemente oder Inhalte (z.B. Videos, Grafiken oder Textbeitr\u00e4ge) darstellen und sind an einem der Facebook Logos erkennbar (wei\u00dfes \u201ef\u201c auf blauer Kachel, den Begriffen &#8222;Like&#8220;, &#8222;Gef\u00e4llt mir&#8220; oder einem \u201eDaumen hoch\u201c-Zeichen) oder sind mit dem Zusatz &#8222;Facebook Social Plugin&#8220; gekennzeichnet. Die Liste und das Aussehen der Facebook Social Plugins kann hier eingesehen werden:\u00a0https:\/\/developers.facebook.com\/docs\/plugins\/.\u2028\u2028Facebook ist unter dem Privacy-Shield-Abkommen zertifiziert und bietet hierdurch eine Garantie, das europ\u00e4ische Datenschutzrecht einzuhalten (https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&amp;status=Active).\u2028\u2028Wenn ein Nutzer eine Funktion dieses Onlineangebotes aufruft, die ein solches Plugin enth\u00e4lt, baut sein Ger\u00e4t eine direkte Verbindung mit den Servern von Facebook auf. Der Inhalt des Plugins wird von Facebook direkt an das Ger\u00e4t des Nutzers \u00fcbermittelt und von diesem in das Onlineangebot eingebunden. Dabei k\u00f6nnen aus den verarbeiteten Daten Nutzungsprofile der Nutzer erstellt werden. Wir haben daher keinen Einfluss auf den Umfang der Daten, die Facebook mit Hilfe dieses Plugins erhebt und informiert die Nutzer daher entsprechend unserem Kenntnisstand.\u2028\u2028Durch die Einbindung der Plugins erh\u00e4lt Facebook die Information, dass ein Nutzer die entsprechende Seite des Onlineangebotes aufgerufen hat. Ist der Nutzer bei Facebook eingeloggt, kann Facebook den Besuch seinem Facebook-Konto zuordnen. Wenn Nutzer mit den Plugins interagieren, zum Beispiel den Like Button bet\u00e4tigen oder einen Kommentar abgeben, wird die entsprechende Information von Ihrem Ger\u00e4t direkt an Facebook \u00fcbermittelt und dort gespeichert. Falls ein Nutzer kein Mitglied von Facebook ist, besteht trotzdem die M\u00f6glichkeit, dass Facebook seine IP-Adresse in Erfahrung bringt und speichert. Laut Facebook wird in Deutschland nur eine anonymisierte IP-Adresse gespeichert.\u2028\u2028Zweck und Umfang der Datenerhebung und die weitere Verarbeitung und Nutzung der Daten durch Facebook sowie die diesbez\u00fcglichen Rechte und Einstellungsm\u00f6glichkeiten zum Schutz der Privatsph\u00e4re der Nutzer, k\u00f6nnen diese den Datenschutzhinweisen von Facebook entnehmen:\u00a0https:\/\/www.facebook.com\/about\/privacy\/.\u2028\u2028Wenn ein Nutzer Facebookmitglied ist und nicht m\u00f6chte, dass Facebook \u00fcber dieses Onlineangebot Daten \u00fcber ihn sammelt und mit seinen bei Facebook gespeicherten Mitgliedsdaten verkn\u00fcpft, muss er sich vor der Nutzung unseres Onlineangebotes bei Facebook ausloggen und seine Cookies l\u00f6schen. Weitere Einstellungen und Widerspr\u00fcche zur Nutzung von Daten f\u00fcr Werbezwecke, sind innerhalb der Facebook-Profileinstellungen m\u00f6glich:\u00a0https:\/\/www.facebook.com\/settings?tab=ads \u00a0oder \u00fcber die US-amerikanische Seite\u00a0http:\/\/www.aboutads.info\/choices\/ \u00a0oder die EU-Seite\u00a0http:\/\/www.youronlinechoices.com\/. Die Einstellungen erfolgen plattformunabh\u00e4ngig, d.h. sie werden f\u00fcr alle Ger\u00e4te, wie Desktopcomputer oder mobile Ger\u00e4te \u00fcbernommen.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Twitter<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Innerhalb unseres Onlineangebotes k\u00f6nnen Funktionen und Inhalte des Dienstes Twitter, angeboten durch die Twitter Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA, eingebunden werden. Hierzu k\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\u00e4chen geh\u00f6ren, mit denen Nutzer Ihr Gefallen betreffend die Inhalte kundtun, den Verfassern der Inhalte oder unsere Beitr\u00e4ge abonnieren k\u00f6nnen. Sofern die Nutzer Mitglieder der Plattform Twitter sind, kann Twitter den Aufruf der o.g. Inhalte und Funktionen den dortigen Profilen der Nutzer zuordnen. Twitter ist unter dem Privacy-Shield-Abkommen zertifiziert und bietet hierdurch eine Garantie, das europ\u00e4ische Datenschutzrecht einzuhalten (https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TORzAAO&amp;status=Active). Datenschutzerkl\u00e4rung: https:\/\/twitter.com\/de\/privacy, Opt-Out: https:\/\/twitter.com\/personalization.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #3a3a3a;\">YouTube<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">F\u00fcr die Einbindung von Videos wird u.a. der Anbieter YouTube genutzt. YouTube wird betrieben von YouTube LLC mit Hauptgesch\u00e4ftssitz in 901 Cherry Avenue, San Bruno, CA 94066, USA. YouTube wird vertreten durch Google Inc. mit Sitz in 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Auf einigen der Internetseiten werden Plugins des Anbieters YouTube verwendet. Wenn Sie die mit einem solchen Plugin versehenen Internetseiten dieser Internetpr\u00e4senz aufrufen \u2013 beispielsweise Videos \u2013, wird eine Verbindung zu den YouTube-Servern hergestellt und dabei das Plugin dargestellt. Hierdurch wird an den YouTube-Server \u00fcbermittelt, welche der Internetseiten Sie besucht haben. Sind Sie dabei als Mitglied bei YouTube eingeloggt, ordnet YouTube diese Information Ihrem pers\u00f6nlichen Benutzerkonto zu. Bei Nutzung des Plugins wie z.B. Anklicken des Start-Buttons eines Videos wird diese Information ebenfalls Ihrem Benutzerkonto zugeordnet. Sie k\u00f6nnen diese Zuordnung verhindern, indem Sie sich vor der Nutzung dieser Internetseite aus ihrem YouTube-Benutzerkonto sowie anderen Benutzerkonten der Firmen YouTube LLC und Google Inc. abmelden und die entsprechenden Cookies der Firmen l\u00f6schen.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Weitere Informationen zur Datenverarbeitung und Hinweise zum Datenschutz durch YouTube (Google) finden Sie unter www.google.de\/intl\/de\/policies\/privacy\/.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Soundcloud<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">F\u00fcr die Einbindung von Audiomaterial wird der Anbieter SoundCloud genutzt. SoundCloud wird betrieben von SoundCloud Limited mit Hauptgesch\u00e4ftssitz in 33 St James Square, London SW1Y 4JS, UK.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Auf einigen dieser Internetseiten werden Plugins des Anbieters SoundCloud verwendet. Wenn Sie die mit einem solchen Plugin versehenen Internetseiten dieser Internetpr\u00e4senz aufrufen \u2013 beispielsweise unsere Mediathek \u2013, wird eine Verbindung zu den SoundCloud-Servern hergestellt und dabei das Plugin dargestellt. Hierdurch wird an den SoundCloud-Server \u00fcbermittelt, welche dieser Internetseiten Sie besucht haben. Sind Sie dabei als Mitglied bei SoundCloud eingeloggt, kann SoundCloud diese Information Ihrem pers\u00f6nlichen Benutzerkonto zuordnen. Bei Nutzung des Plugins wie z.B. Anklicken des Start-Buttons einer Audiodatei wird diese Information ebenfalls Ihrem Benutzerkonto zugeordnet. Sie k\u00f6nnen diese Zuordnung verhindern, indem Sie sich vor der Nutzung unserer Internetseite aus ihrem SoundCloud-Benutzerkonto abmelden und die entsprechenden Cookies von SoundCloud l\u00f6schen.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Weitere Informationen zur Datenverarbeitung und Hinweise zum Datenschutz durch SoundCloud finden Sie unter https:\/\/soundcloud.com\/pages\/privacy.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Instagram<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Innerhalb unseres Onlineangebotes k\u00f6nnen Funktionen und Inhalte des Dienstes Instagram, angeboten durch die Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA, eingebunden werden. Hierzu k\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\u00e4chen geh\u00f6ren, mit denen Nutzer Inhalte dieses Onlineangebotes innerhalb von Instagram teilen k\u00f6nnen. Sofern die Nutzer Mitglieder der Plattform Instagram sind, kann Instagram den Aufruf der o.g. Inhalte und Funktionen den dortigen Profilen der Nutzer zuordnen. Datenschutzerkl\u00e4rung von Instagram: http:\/\/instagram.com\/about\/legal\/privacy\/.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Google AdWords<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nAuf dieser Internetseite wurde Google AdWords integriert. Google AdWords ist ein Dienst zur Internetwerbung, der es Werbetreibenden gestattet, sowohl Anzeigen in den Suchmaschinenergebnissen von Google als auch im Google-Werbenetzwerk zu schalten. Google AdWords erm\u00f6glicht es einem Werbetreibenden, vorab bestimmte Schl\u00fcsselw\u00f6rter festzulegen, mittels derer eine Anzeige in den Suchmaschinenergebnissen von Google ausschlie\u00dflich dann angezeigt wird, wenn der Nutzer mit der Suchmaschine ein schl\u00fcsselwortrelevantes Suchergebnis abruft. Im Google-Werbenetzwerk werden die Anzeigen mittels eines automatischen Algorithmus und unter Beachtung der zuvor festgelegten Schl\u00fcsselw\u00f6rter auf themenrelevanten Internetseiten verteilt.\u2028Betreibergesellschaft der Dienste von Google AdWords ist die Google Inc., 1600 Amphitheatre Pkwy, Mountain View, CA 94043-1351, USA.\u2028Der Zweck von Google AdWords ist die Bewerbung dieser Internetseite durch die Einblendung von interessenrelevanter Werbung auf den Internetseiten von Drittunternehmen und in den Suchmaschinenergebnissen der Suchmaschine Google und eine Einblendung von Fremdwerbung auf unserer Internetseite. \u2028Gelangt eine betroffene Person \u00fcber eine Google-Anzeige auf diese Internetseite, wird auf dem informationstechnologischen System der betroffenen Person durch Google ein sogenannter Conversion-Cookie abgelegt. Was Cookies sind, wurde oben bereits erl\u00e4utert. Ein Conversion-Cookie verliert nach drei\u00dfig Tagen seine G\u00fcltigkeit und dient nicht zur Identifikation der betroffenen Person. \u00dcber den Conversion-Cookie wird, sofern das Cookie noch nicht abgelaufen ist, nachvollzogen, ob bestimmte Unterseiten, beispielsweise der Warenkorb von einem Online-Shop-System, auf unserer Internetseite aufgerufen wurden. Durch den Conversion-Cookie kann sowohl der Websitebetreiber als auch Google nachvollziehen, ob eine betroffene Person, die \u00fcber eine AdWords-Anzeige auf unsere Internetseite gelangt ist, einen Umsatz generierte, also einen Warenkauf vollzogen oder abgebrochen hat.\u2028Die durch die Nutzung des Conversion-Cookies erhobenen Daten und Informationen werden von Google verwendet, um Besuchsstatistiken f\u00fcr unsere Internetseite zu erstellen. Diese Besuchsstatistiken werden durch den Betreiber dieser Internetseite wiederum genutzt, um die Gesamtanzahl der Nutzer zu ermitteln, welche \u00fcber AdWords-Anzeigen an uns vermittelt wurden, also um den Erfolg oder Misserfolg der jeweiligen AdWords-Anzeige zu ermitteln und um unsere AdWords-Anzeigen f\u00fcr die Zukunft zu optimieren. Weder Irina K\u00fchn noch andere Werbekunden von Google-AdWords erhalten Informationen von Google, mittels derer die betroffene Person identifiziert werden k\u00f6nnte.\u2028Mittels des Conversion-Cookies werden personenbezogene Informationen, beispielsweise die durch die betroffene Person besuchten Internetseiten, gespeichert. Bei jedem Besuch unserer Internetseiten werden demnach personenbezogene Daten, einschlie\u00dflich der IP-Adresse des von der betroffenen Person genutzten Internetanschlusses, an Google in den Vereinigten Staaten von Amerika \u00fcbertragen. Diese personenbezogenen Daten werden durch Google in den Vereinigten Staaten von Amerika gespeichert. Google gibt diese \u00fcber das technische Verfahren erhobenen personenbezogenen Daten unter Umst\u00e4nden an Dritte weiter.\u2028Die betroffene Person kann die Setzung von Cookies durch unsere Internetseite, wie oben bereits dargestellt, jederzeit mittels einer entsprechenden Einstellung des genutzten Internetbrowsers verhindern und damit der Setzung von Cookies dauerhaft widersprechen. Eine solche Einstellung des genutzten Internetbrowsers w\u00fcrde auch verhindern, dass Google einen Conversion-Cookie auf dem informationstechnologischen System der betroffenen Person setzt. Zudem kann ein von Google AdWords bereits gesetzter Cookie jederzeit \u00fcber den Internetbrowser oder andere Softwareprogramme gel\u00f6scht werden.\u2028Ferner besteht f\u00fcr die betroffene Person die M\u00f6glichkeit, der interessenbezogenen Werbung durch Google zu widersprechen. Hierzu muss die betroffene Person von jedem der von ihr genutzten Internetbrowser aus den Link www.google.de\/settings\/ads aufrufen und dort die gew\u00fcnschten Einstellungen vornehmen.\u2028Weitere Informationen und die geltenden Datenschutzbestimmungen von Google k\u00f6nnen unter https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ abgerufen werden.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Ihre Rechte als von der Datenverarbeitung Betroffener<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nNach den anwendbaren Gesetzen haben Sie verschiedene Rechte bez\u00fcglich ihrer personenbezogenen Daten. M\u00f6chten Sie diese Rechte geltend machen, so richten Sie Ihre Anfrage bitte per E-Mail oder per Post unter eindeutiger Identifizierung Ihrer Person an die genannte Adresse. Nachfolgend finden Sie eine \u00dcbersicht \u00fcber Ihre Rechte.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Recht auf Best\u00e4tigung und Auskunft<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben jederzeit das Recht, von uns eine Best\u00e4tigung dar\u00fcber zu erhalten, ob Sie betreffende personenbezogene Daten verarbeitet werden. Ist dies der Fall, so haben Sie das Recht, von uns eine unentgeltliche Auskunft \u00fcber die zu Ihnen gespeicherten personenbezogenen Daten nebst einer Kopie dieser Daten zu erlangen. Desweiteren besteht ein Recht auf folgende Informationen:<\/span><\/p>\n<p><span style=\"color: #3a3a3a;\">1. die Verarbeitungszwecke;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">2. die Kategorien personenbezogener Daten, die verarbeitet werden;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">3. die Empf\u00e4nger oder Kategorien von Empf\u00e4ngern, gegen\u00fcber denen die personenbezogenen Daten offengelegt worden sind oder noch offengelegt werden, insbesondere bei Empf\u00e4ngern in Drittl\u00e4ndern oder bei internationalen rganisationen;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">4. falls m\u00f6glich die geplante Dauer, f\u00fcr die die personenbezogenen Daten gespeichert werden, oder, falls dies nicht m\u00f6glich ist, die Kriterien f\u00fcr die Festlegung dieser Dauer;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">5. das Bestehen eines Rechts auf Berichtigung oder L\u00f6schung der Sie betreffenden personenbezogenen Daten oder auf Einschr\u00e4nkung der Verarbeitung durch den Verantwortlichen oder eines Widerspruchsrechts gegen diese Verarbeitung;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">6. das Bestehen eines Beschwerderechts bei einer Aufsichtsbeh\u00f6rde;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">7. wenn die personenbezogenen Daten nicht bei Ihnen erhoben werden, alle verf\u00fcgbaren Informationen \u00fcber die Herkunft der Daten;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">8. das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs\u00e4tze 1 und 4 DSGVO und \u2013 zumindest in diesen F\u00e4llen \u2013 aussagekr\u00e4ftige Informationen \u00fcber die involvierte Logik sowie die Tragweite und die angestrebten Auswirkungen einer derartigen Verarbeitung f\u00fcr Sie.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Werden personenbezogene Daten an ein Drittland oder an eine internationale Organisation \u00fcbermittelt, so haben Sie das Recht, \u00fcber die geeigneten Garantien gem\u00e4\u00df Artikel 46 DSGVO im Zusammenhang mit der \u00dcbermittlung unterrichtet zu werden.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Recht auf Berichtigung<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben das Recht, von uns unverz\u00fcglich die Berichtigung Sie betreffender unrichtiger personenbezogener Daten zu verlangen. Unter Ber\u00fccksichtigung der Zwecke der haben Sie das Recht, die Vervollst\u00e4ndigung unvollst\u00e4ndiger personenbezogener Daten \u2013 auch mittels einer erg\u00e4nzenden Erkl\u00e4rung \u2013 zu verlangen.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Recht auf L\u00f6schung (\u201eRecht auf Vergessenwerden\u201c)<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben das Recht, von uns zu verlangen, dass Sie betreffende personenbezogene Daten unverz\u00fcglich gel\u00f6scht werden, und wir sind verpflichtet, personenbezogene Daten unverz\u00fcglich zu l\u00f6schen, sofern einer der folgenden Gr\u00fcnde zutrifft:<\/span><br \/>\n<span style=\"color: #3a3a3a;\">1. Die personenbezogenen Daten sind f\u00fcr die Zwecke, f\u00fcr die sie erhoben oder auf sonstige Weise verarbeitet wurden, nicht mehr notwendig.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">2. Sie widerrufen Ihre Einwilligung, auf die sich die Verarbeitung gem\u00e4\u00df Artikel 6 Absatz 1 DSGVO Buchstabe a oder Artikel 9 Absatz 2 Buchstabe a DSGVO st\u00fctzte, und es fehlt an einer anderweitigen Rechtsgrundlage f\u00fcr die Verarbeitung.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">3. Sie legen gem\u00e4\u00df Artikel 21 Absatz 1 DSGVO Widerspruch gegen die Verarbeitung ein und es liegen keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vor, oder Sie legen gem\u00e4\u00df Artikel 21 Absatz 2 DSGVO Widerspruch gegen die Verarbeitung ein.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">4. Die personenbezogenen Daten wurden unrechtm\u00e4\u00dfig verarbeitet.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">5. Die L\u00f6schung der personenbezogenen Daten ist zur Erf\u00fcllung einer rechtlichen Verpflichtung nach dem Unionsrecht oder dem Recht der Mitgliedstaaten erforderlich, dem wir unterliegen.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">6. Die personenbezogenen Daten wurden in Bezug auf angebotene Dienste der Informationsgesellschaft gem\u00e4\u00df Artikel 8 Absatz 1 DSGVO erhoben.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Haben wir die personenbezogenen Daten \u00f6ffentlich gemacht und sind wir gem\u00e4\u00df zu deren L\u00f6schung verpflichtet, so treffen wir unter Ber\u00fccksichtigung der verf\u00fcgbaren Technologie und der Implementierungskosten angemessene Ma\u00dfnahmen, auch technischer Art, um f\u00fcr die<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Datenverarbeitung Verantwortliche, die die personenbezogenen Daten verarbeiten, dar\u00fcber zu informieren, dass Sie von ihnen die L\u00f6schung aller Links zu diesen personenbezogenen Daten oder von Kopien oder Replikationen dieser personenbezogenen Daten verlangt hat.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Recht auf Einschr\u00e4nkung der Verarbeitung<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben das Recht, von uns die Einschr\u00e4nkung der Verarbeitung zu verlangen, wenn eine der folgenden Voraussetzungen gegeben ist:<\/span><br \/>\n<span style=\"color: #3a3a3a;\">1. die Richtigkeit der personenbezogenen Daten wird von Ihnen bestritten, und zwar f\u00fcr eine Dauer, die es uns erm\u00f6glicht, die Richtigkeit der personenbezogenen Daten zu \u00fcberpr\u00fcfen,<\/span><br \/>\n<span style=\"color: #3a3a3a;\">2. die Verarbeitung unrechtm\u00e4\u00dfig ist und Sie die L\u00f6schung der personenbezogenen Daten ablehnten und stattdessen die Einschr\u00e4nkung der Nutzung der personenbezogenen Daten verlangt;<\/span><br \/>\n<span style=\"color: #3a3a3a;\">3. wir die personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht l\u00e4nger ben\u00f6tigen, Sie die Daten jedoch zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigten, oder<\/span><br \/>\n<span style=\"color: #3a3a3a;\">4. Sie Widerspruch gegen die Verarbeitung gem\u00e4\u00df Artikel 21 Absatz 1 DSGVO eingelegt haben, solange noch nicht feststeht, ob die berechtigten Gr\u00fcnde unseres Unternehmens gegen\u00fcber den Ihren \u00fcberwiegen.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Recht auf Daten\u00fcbertragbarkeit<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben das Recht, die Sie betreffenden personenbezogenen Daten, die uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten, und Sie haben das Recht, diese Daten einem anderen Verantwortlichen ohne Behinderung durch uns zu \u00fcbermitteln, sofern<\/span><br \/>\n<span style=\"color: #3a3a3a;\">1. die Verarbeitung auf einer Einwilligung gem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe a DSGVO oder Artikel 9 Absatz 2 Buchstabe a DSGVO oder auf einem Vertraggem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe b DSGVO beruht und<\/span><br \/>\n<span style=\"color: #3a3a3a;\">2. die Verarbeitung mithilfe automatisierter Verfahren erfolgt.<\/span><br \/>\n<span style=\"color: #3a3a3a;\">Bei der Aus\u00fcbung ihres Rechts auf Daten\u00fcbertragbarkeit gem\u00e4\u00df Absatz 1 haben Sie das Recht, zu erwirken, dass die personenbezogenen Daten direkt von uns einem anderen Verantwortlichen \u00fcbermittelt werden, soweit dies technisch machbar ist.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Widerspruchsrecht<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung sie betreffender personenbezogener Daten, die aufgrund von Artikel 6 Absatz 1 Buchstaben e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Wir verarbeiten die personenbezogenen Daten nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, die Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen, oder die Verarbeitung dient der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen.<\/span><\/p>\n<h3><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Auskunftsrecht<\/span><\/h3>\n<p><span style=\"color: #3a3a3a;\">Sie haben jederzeit das Recht auf Auskunft \u00fcber die bez\u00fcglich Ihrer Person gespeicherten Daten, deren Herkunft und Empf\u00e4nger sowie den Zweck der Speicherung. Auskunft \u00fcber die gespeicherten Daten erhalten Sie unter mail@irinakuehn.de<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Weitergabe von Daten an Dritte, Keine Daten\u00fcbertragung ins Nicht-EU-Ausland<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nGrunds\u00e4tzlich verwenden wir Ihre personenbezogenen Daten nur innerhalb unseres Unternehmens. Wenn und soweit wir Dritte im Rahmen der Erf\u00fcllung von Vertr\u00e4gen einschalten (etwa Logistik-Dienstleister) erhalten diese personenbezogene Daten nur in dem Umfang, in welchem die \u00dcbermittlung f\u00fcr die entsprechende Leistung erforderlich ist. F\u00fcr den Fall, dass wir bestimmte Teile der Datenverarbeitung auslagern (\u201eAuftragsverarbeitung\u201c), verpflichten wir Auftragsverarbeiter vertraglich dazu, personenbezogene Daten nur im Einklang mit den Anforderungen der Datenschutzgesetze zu verwenden und den Schutz der Rechte der betroffenen Person zu gew\u00e4hrleisten. Eine Daten\u00fcbertragung an Stellen oder Personen au\u00dferhalb der EU au\u00dferhalb der in dieser Erkl\u00e4rung in Punkt 2.3 genannten F\u00e4llen findet nicht statt und ist nicht geplant.<\/span><\/p>\n<h2><span style=\"color: #3a3a3a;\"><strong><br \/>\n<\/strong>Weitere Informationen<\/span><\/h2>\n<p><span style=\"color: #3a3a3a;\"><br \/>\nWenn Sie Fragen haben, die Ihnen diese Datenschutzerkl\u00e4rung nicht beantworten konnte oder wenn Sie zu einem Punkt vertiefte Informationen w\u00fcnschen, wenden Sie sich bitte jederzeit an<\/span> <a href=\"mailto:mail@irinakuehn.de\">mail@irinakuehn.de<\/a><\/p>\n<\/div>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid\" style=' text-align:left;'><div class=\"full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Die nachfolgende Datenschutzerkl\u00e4rung gilt f\u00fcr die Nutzung der Webseite www.irinakuehn.de (nachfolgend \u201eWebsite\u201c). Wir messen dem Datenschutz gro\u00dfe Bedeutung bei. Die Erhebung und Verarbeitung Ihrer personenbezogenen Daten geschieht unter Beachtung der geltenden datenschutzrechtlichen Vorschriften, insbesondere der EU-Datenschutzgrundverordnung (DSGVO). WPersonenbezogene Daten werden auf dieser Webseite nur im...","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"open","ping_status":"open","template":"full_width.php","meta":{"_mi_skip_tracking":false},"_links":{"self":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/pages\/19438"}],"collection":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/comments?post=19438"}],"version-history":[{"count":9,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/pages\/19438\/revisions"}],"predecessor-version":[{"id":20140,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/pages\/19438\/revisions\/20140"}],"wp:attachment":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media?parent=19438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}