{"id":20166,"date":"2023-07-28T14:38:37","date_gmt":"2023-07-28T12:38:37","guid":{"rendered":"https:\/\/irinakuehn.de\/?p=20166"},"modified":"2023-07-28T14:40:05","modified_gmt":"2023-07-28T12:40:05","slug":"230728_neuer-song-out-of-tune-plain-folly","status":"publish","type":"post","link":"https:\/\/irinakuehn.de\/en\/230728_neuer-song-out-of-tune-plain-folly\/","title":{"rendered":"Neuer PLAIN FOLLY Song OUT OF TUNE"},"content":{"rendered":"<p>Seit heute ist der <strong>neue Plain Folly Song <\/strong>OUT OF TUNE auf allen digitalen Audio-Plattformen zum Streamen und Kaufen erh\u00e4ltlich!<\/p>\n<p>OUT OF TUNE ist der vierte Song aus dem kommenden Album der Indie Pop K\u00fcnstlerin, S\u00e4ngerin und Multi-Instrumentalistin Irina K\u00fchn aka Plain Folly, bei dem sie erneut mit Produzent Tom Schenk und Schlagzeuger Moritz M\u00fcller zusammenarbeitete.<\/p>\n<p>Zwischen Kate Bush, Regina Spektor und Tori Amos oszilliert das entfesselte OUT OF TUNE. Teils Wiegenlied und teils Saloon-Ballade aus den S\u00fcdstaaten mit einem hinrei\u00dfenden Pianoarrangement, geht Plain Folly hier auffallend offensiv, k\u00f6rperlich, fordernd vor: Ein loderndes, begehrendes, dezidiert feminines Liebeslied \u00fcber zwei Menschen, die nicht voneinander lassen k\u00f6nnen. Obwohl sie das eigentlich sollten. Plain Follys ganz pers\u00f6nliche Murder Ballad zwischen Ravel und Americana.<\/p>\n<p>SONG CREDITS<br \/>\nMusic &#038; Lyrics by Irina K\u00fchn<br \/>\nVocals, Piano, Guitars, Synths &#038; Bass: Irina K\u00fchn<br \/>\nDrums: Moritz M\u00fcller<br \/>\nRecording, Engineering, Mix &#038; Mastering by Tom Schenk (Tankraum Studio)<br \/>\nAdditional Recordings by Irina K\u00fchn (Red Hall Studios)<br \/>\nProduced by Tom Schenk <\/p>\n<p>Klickt einfach auf den folgenden Link, um den Song beim Anbieter eurer Wahl zu h\u00f6ren: <a href=\"https:\/\/plainfolly.com\/listentooutoftune\/\" target=\"_blank\" rel=\"noopener\">OUT OF TUNE<\/a><\/p>\n<p><a href=\"\/en\/news\/\">\u2190\u00a0ZUR\u00dcCK<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Seit heute ist der neue Plain Folly Song OUT OF TUNE auf allen digitalen Audio-Plattformen zum Streamen und Kaufen erh\u00e4ltlich! OUT OF TUNE ist der vierte Song aus dem kommenden Album der Indie Pop K\u00fcnstlerin, S\u00e4ngerin und Multi-Instrumentalistin Irina K\u00fchn aka Plain Folly, bei dem&#8230;<\/p>","protected":false},"author":3,"featured_media":20163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[202],"tags":[],"_links":{"self":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20166"}],"collection":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/comments?post=20166"}],"version-history":[{"count":2,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20166\/revisions"}],"predecessor-version":[{"id":20168,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20166\/revisions\/20168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media\/20163"}],"wp:attachment":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media?parent=20166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/categories?post=20166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/tags?post=20166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}