{"id":20271,"date":"2025-03-17T12:32:53","date_gmt":"2025-03-17T11:32:53","guid":{"rendered":"https:\/\/irinakuehn.de\/?p=20271"},"modified":"2025-03-17T12:33:11","modified_gmt":"2025-03-17T11:33:11","slug":"250317_premiere-von-amelie-das-musical","status":"publish","type":"post","link":"https:\/\/irinakuehn.de\/en\/250317_premiere-von-amelie-das-musical\/","title":{"rendered":"Premiere von AM\u00c9LIE &#8211; DAS MUSICAL"},"content":{"rendered":"<div class=\"\" data-block=\"true\" data-editor=\"2eh6s\" data-offset-key=\"bcde1-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"bcde1-0-0\"><span data-offset-key=\"bcde1-0-0\">AM\u00c9LIE- DAS MUSICAL \u2764\ufe0f\ud83c\uddeb\ud83c\uddf7 Ein wundervolles Premierenwochenende mit ausverkauften Shows und eine intensive, erf\u00fcllende Probewoche liegen hinter mir und ich k\u00f6nnte nicht gl\u00fccklicher sein! Vielen Dank an alle, die unser wundersch\u00f6nes Musical bereits besucht haben &#8211; und f\u00fcr alle, die es noch nicht geschafft haben: F\u00fcr die drei Shows am kommenden Wochenende gibt es noch Karten unter <a href=\"https:\/\/kulturwelt-lb.de\/amelie.html\">https:\/\/kulturwelt-lb.de\/amelie.html<\/a><br \/>\n<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"2eh6s\" data-offset-key=\"fivla-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"fivla-0-0\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>AM\u00c9LIE- DAS MUSICAL \u2764\ufe0f\ud83c\uddeb\ud83c\uddf7 Ein wundervolles Premierenwochenende mit ausverkauften Shows und eine intensive, erf\u00fcllende Probewoche liegen hinter mir und ich k\u00f6nnte nicht gl\u00fccklicher sein! Vielen Dank an alle, die unser wundersch\u00f6nes Musical bereits besucht haben &#8211; und f\u00fcr alle, die es noch nicht geschafft haben:&#8230;<\/p>","protected":false},"author":3,"featured_media":20272,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[209,200],"tags":[],"_links":{"self":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20271"}],"collection":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/comments?post=20271"}],"version-history":[{"count":1,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20271\/revisions"}],"predecessor-version":[{"id":20273,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20271\/revisions\/20273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media\/20272"}],"wp:attachment":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media?parent=20271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/categories?post=20271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/tags?post=20271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}