{"id":20290,"date":"2025-10-17T08:53:28","date_gmt":"2025-10-17T06:53:28","guid":{"rendered":"https:\/\/irinakuehn.de\/?p=20290"},"modified":"2026-03-22T12:12:52","modified_gmt":"2026-03-22T11:12:52","slug":"251017_wiederaufnahme-amelie-das-musical","status":"publish","type":"post","link":"https:\/\/irinakuehn.de\/en\/251017_wiederaufnahme-amelie-das-musical\/","title":{"rendered":"&#8222;Am\u00e9lie &#8211; Das Musical&#8220; &#8211; ab 14. November 2025"},"content":{"rendered":"<p>Nur noch 4 Wochen: Nach dem fabelhaften Premieren-Auftakt im M\u00e4rz 2025 mit sechs ausverkauften Shows kehrt Am\u00e9lie zur\u00fcck auf die B\u00fchne &#8211; und damit auch ich als Caf\u00e9besitzerin Suzanne!<\/p>\n<p>Das St\u00fcck basiert auf dem erfolgreichen franz\u00f6sischen Film \u201eDie fabelhafte Welt der Am\u00e9lie\u201c und erz\u00e4hlt die Geschichte einer sch\u00fcchternen und fantasievollen jungen Pariserin: Am\u00e9lie beschlie\u00dft, das Leben der Menschen um sie herum zu vers\u00fc\u00dfen, indem sie kleine, geheimnisvolle Taten der Freundlichkeit vollbringt. W\u00e4hrend sie versucht, anderen zu helfen und ihre eigenen Tr\u00e4ume zu verwirklichen, entdeckt sie auch die Herausforderungen der Liebe und der zwischenmenschlichen Beziehungen. Doch als sich ihr selbst die Chance auf Liebe bietet, erkennt Am\u00e9lie, dass sie alles riskieren muss, um ihr eigenes Gl\u00fcck zu finden &#8230;<\/p>\n<p><b>Die Termine:<\/b><\/p>\n<p>Freitag, 14.11.2025 &#8211; 19:30 Uhr<br \/>\nSamstag 15.11.2025 &#8211; 19:30 Uhr<br \/>\nSonntag 16.11.2025 &#8211; 17:00 Uhr<br \/>\nDonnerstag 20.11.2025 &#8211; 19:30 Uhr<br \/>\nFreitag, 21.11.2025 &#8211; 19:30 Uhr<br \/>\nSamstag 22.11.2025 &#8211; 19:30 Uhr<br \/>\nSonntag 23.11.2025 &#8211; 17:00 Uhr<\/p>\n<p>Alle Infos zum Musical, zur Location und den Tickets findet ihr unter diesem Link:<br \/>\n<a href=\"https:\/\/kulturwelt-lb.de\/amelie.html\">https:\/\/kulturwelt-lb.de\/amelie.html<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Nur noch 4 Wochen: Nach dem fabelhaften Premieren-Auftakt im M\u00e4rz 2025 mit sechs ausverkauften Shows kehrt Am\u00e9lie zur\u00fcck auf die B\u00fchne &#8211; und damit auch ich als Caf\u00e9besitzerin Suzanne! Das St\u00fcck basiert auf dem erfolgreichen franz\u00f6sischen Film \u201eDie fabelhafte Welt der Am\u00e9lie\u201c und erz\u00e4hlt die&#8230;<\/p>","protected":false},"author":3,"featured_media":20415,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[200],"tags":[],"_links":{"self":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20290"}],"collection":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/comments?post=20290"}],"version-history":[{"count":1,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20290\/revisions"}],"predecessor-version":[{"id":20292,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/posts\/20290\/revisions\/20292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media\/20415"}],"wp:attachment":[{"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/media?parent=20290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/categories?post=20290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/irinakuehn.de\/en\/wp-json\/wp\/v2\/tags?post=20290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}